{"id":11454,"date":"2022-02-03T08:14:56","date_gmt":"2022-02-03T08:14:56","guid":{"rendered":"http:\/\/milanosiamonoi.com\/?page_id=11454"},"modified":"2023-04-28T08:46:45","modified_gmt":"2023-04-28T08:46:45","slug":"1957-1958-amatori-mi-e-bocconi","status":"publish","type":"page","link":"https:\/\/www.milanosiamonoi.com\/index.php\/campionati\/dal-1950-al-1959-anni-doro\/1957-1958-amatori-mi-e-bocconi\/","title":{"rendered":"1957\/1958 Amatori Mi e Bocconi"},"content":{"rendered":"\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1.jpg\" alt=\"\" class=\"wp-image-6245\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1-150x150.jpg 150w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1-100x100.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1-50x50.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1-25x25.jpg 25w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/04\/logo-amatoriok-300x300-1-90x90.jpg 90w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td>Presidente<\/td><td>Floriano Mainoldi<\/td><\/tr><tr><td>Allenatore<\/td><td>Carlo Signorini<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Ruolo<\/td><td><strong>Giocatori con almeno una presenza in prima squadra.<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">P<\/td><td>Andrea Balzani, Piero Misul, Gino Rinaldi.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">D<\/td><td>Franco Canepa, Michele Ferrante, Mario Frigerio, Andrea Lusena, Enzo Seveso.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">A<\/td><td>Giancarlo Bonalanza, Cesare Bressan, Giovanni Ceserani, Adriano Cremonesi, Sarino Oriana, Michele Ottonello, Renato Lesma, Renato Rossi, Walter Schmid, Vicario, Riccardo Vivanti, Ottavio Wild.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Con il passaggio di Paolo Marchi al Milaninter il posto da titolare davanti alla gabbia \u00e8 di Andrea Balzani, il rientrante Piero Misul gli far\u00e0 da secondo.  Emilio Delfino ha scelto il Lugano, ma con i bianconeri giocher\u00e0 solo amichevoli e tornei; in campionato serve inevitabilmente un canadese. Stabilmente in prima squadra Giovanni Ceserani, Andrea Lusena e Walter Schmid. Tra gli allievi un occhio di riguardo per Gino Rinaldi (portiere) e Cesare Bressan (attaccante).<\/p>\n\n\n\n<p class=\"has-text-align-center\">Al campionato di Promozione partecipano dodici squadre, che vengono divise in tre gironi da quattro. Nel raggruppamento occidemtale non c&#8217;\u00e8 la Valpe, con lo scioglimento del Fiat hockey ritorna in attivit\u00e0 il Torino. Per Amatori Milano e Bocconi una rivale di riguardo: l&#8217;Asiago. Si parte il 16 dicembre 1957 con un primo derby da scintille.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo.jpg\" alt=\"\" class=\"wp-image-11451\" width=\"563\" height=\"496\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo.jpg 655w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo-300x265.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo-100x88.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo-50x44.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.16-PA-AmM-Boc-4-2-e-giudice-sportivo-25x22.jpg 25w\" sizes=\"(max-width: 563px) 100vw, 563px\" \/><figcaption><em>Da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong>Torino, 20 dicembre 1957 &#8211; Camp. italiano di Promozione<\/strong> &#8211; <strong>Girone A<\/strong><\/td><\/tr><tr><td>Torino-Amatori Milano 3-5 (0-2; 0-1; 3-2)<\/td><\/tr><tr><td>Torino: De Marchi; Cicogna, Banioni; Bianchini, Ilotte; Doglio, Colombano, F. Castiglioni; Arlorio, Berra, Saglietti.<\/td><\/tr><tr><td>Amatori Milano: Misul; Ferrante, A. Lusena; Seveso, Canepa; Schmid, Ceserani, Wild; R. Rossi, Oriana, Lesma; Cremonesi, Ottonello, Bonalanza.<\/td><\/tr><tr><td>Reti: 1\u00b0t. 3&#8242; Ceserani, 13&#8242; Wild. 2\u00b0t. 7&#8242; R. Rossi. 3\u00b0t. <em>3&#8242; Doglio,<\/em>  4&#8242; Ceserani, <em>4&#8217;30&#8221; F. Castiglioni, 5&#8217;19&#8221; Berra,<\/em> 14&#8217;07&#8221; R. Rossi.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Il campionato dell&#8217;Amatori va in letargo, se ne riparler\u00e0 nell&#8217;ultima settimana di gennaio. Si apre una piccola parentesi di incontri a Madesimo e all&#8217;estero con Lugano e Briancon.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>195<\/strong>8<\/td><td><strong>Madesimo &#8211; Coppa Hoffmann<\/strong><\/td><td><strong>Risultato<\/strong><\/td><\/tr><tr><td>5 gennaio<\/td><td>Lugano-Amatori Milano<\/td><td>11-3<\/td><\/tr><tr><td><\/td><td><strong>Lugano &#8211; Partita amichevole.<\/strong><\/td><td><\/td><\/tr><tr><td>6 gennaio<\/td><td>Lugano-Amatori Milano<\/td><td>14-3 (5-2; 7-0; 2-1) <\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"385\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop.jpg\" alt=\"\" class=\"wp-image-11480\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop.jpg 400w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop-300x289.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop-100x96.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop-50x48.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.06-Luga-AmM-14-3-GiordelPop-25x25.jpg 25w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><figcaption><em>Articolo da &#8220;Il Giornale del Popolo&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Briancon &#8211; Partite amichevoli.<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>18 gennaio<\/td><td>Briancon-Amatori Milano<\/td><td>9-2<\/td><\/tr><tr><td>19 gennaio<\/td><td>Briancon-Amatori Milano<\/td><td>10-2<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Dal 23 gennaio all&#8217;8 febbraio volata finale per il primato nel girone A.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Camp. italiano di Promozione &#8211; Girone A<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>Milano, 23 gennaio<\/td><td>Amatori Milano-Torino<\/td><td>6-2<\/td><\/tr><tr><td>Asiago, 26 gennaio<\/td><td>Asiago-Amatori Milano <\/td><td>3-3<\/td><\/tr><tr><td>Milano, 29 gennaio<\/td><td>Bocconi-Amatori Milano<\/td><td>2-4 (0-3; 2-0; 0-1)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Ultima partita da dentro o fuori, in caso di risultato nullo la differenza reti \u00e8 favorevole all&#8217;Asiago, l&#8217;Amatori deve solo vincere: in pratica quello che si gioca al  Piranesi \u00e8 uno spareggio.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3.jpg\" alt=\"\" class=\"wp-image-11493\" width=\"298\" height=\"648\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3.jpg 309w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3-138x300.jpg 138w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3-46x100.jpg 46w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3-23x50.jpg 23w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.08-PA-AmM-Asia-5-3-11x25.jpg 11w\" sizes=\"(max-width: 298px) 100vw, 298px\" \/><figcaption>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>Classifiche dei tre gironi del campionato di Promozione 1957\/58.<\/strong><\/td><\/tr><tr><td>Girone A: Amatori Milano punti 11, Asiago 9, Torino e Bocconi 2.<\/td><\/tr><tr><td>Girone B: SSV Bozen punti 12, Vipiteno 8, Renon 4, Latemar Bz 0.<\/td><\/tr><tr><td>Girone C: M.te Civetta Alleghe punti 12, Am. Cortina 8, Comelico e Agordo 2.<\/td><\/tr><tr><td><strong>Amatori Milano, SSV Bozen e Monte Civetta Alleghe al girone finale.<\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Il girone finale si svolge a Bolzano dal 13 al 15 febbraio. Si comincia con SSV-Monte Civetta Alleghe. L&#8217;Amatori affronta le due squadre successivamente.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Bolzano &#8211; Girone finale del camp. di Promozione.<\/strong><\/td><\/tr><tr><td>13 febbraio<\/td><td>SSV Bozen-M.te Civetta Alleghe 4-5 (3-1; 0-3; 1-1)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist.jpg\" alt=\"\" class=\"wp-image-11505\" width=\"516\" height=\"436\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist.jpg 611w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist-300x254.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist-100x85.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist-50x42.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.14-PGF-AmM-MCA-2-2-Adige-sist-25x21.jpg 25w\" sizes=\"(max-width: 516px) 100vw, 516px\" \/><figcaption>Articolo parziale da &#8220;L&#8217;Adige&#8221;.<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1.jpg\" alt=\"\" class=\"wp-image-11506\" width=\"334\" height=\"502\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1.jpg 347w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1-199x300.jpg 199w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1-66x100.jpg 66w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1-33x50.jpg 33w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.15-PGF-AmM-Ssv-11-1-17x25.jpg 17w\" sizes=\"(max-width: 334px) 100vw, 334px\" \/><figcaption>Da &#8220;La Gazzetta dello Sport&#8221;.<\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"394\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post.jpg\" alt=\"\" class=\"wp-image-11507\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post.jpg 646w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post-300x183.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post-100x61.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post-50x30.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.17-PGF-AmM-Ssv-11-1-post-25x15.jpg 25w\" sizes=\"(max-width: 646px) 100vw, 646px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">L&#8217;Amatori vince il campionato grazie alla migliore differenza reti nei confronti del Monte Civetta. Per poter accedere alla serie A lo scoglio si chiama Ortisei, da incontrare in partita secca nel mese di marzo.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td>Classifica finale<\/td><td class=\"has-text-align-center\" data-align=\"center\">P.ti<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gol fatti<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gol subiti<\/td><\/tr><tr><td><strong>1 Amatori Milano<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>3<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>13<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>3<\/strong><\/td><\/tr><tr><td>2 Monte Civetta Alleghe<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>3 SSV Bozen<\/td><td class=\"has-text-align-center\" data-align=\"center\">0<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">16<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Il match di spareggio si gioca a Bolzano il 3 marzo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"402\" height=\"424\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist.jpg\" alt=\"\" class=\"wp-image-11508\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist.jpg 402w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist-284x300.jpg 284w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist-95x100.jpg 95w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist-47x50.jpg 47w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.03.03-A-Orti-AmM-5-1-Adige-sist-25x25.jpg 25w\" sizes=\"(max-width: 402px) 100vw, 402px\" \/><figcaption><em>Articolo da &#8220;L&#8217;Adige&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Vittoria dell&#8217;Ortisei su di un Amatori incompleto: assenti Ferrante, Oriana e Wild. I gardenesi restano in serie A grazie a un&#8217;impostazione di gioco migliore, ma devono molto alle iniziative individuali del canadese Mc Neil.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>Classifica marcatori stagionali Amatori Milano.<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Reti<\/td><\/tr><tr><td>Giovanni Ceserani, Renato Rossi e Walter Schmid<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><\/tr><tr><td>Ottavio Wild <\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><\/tr><tr><td>Renato Lesma<\/td><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><\/tr><tr><td>Cesare Bressan<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Franco Canepa, Andrea Lusena <\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Autogol<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Mancano i marcatori di 16 reti: Lugano (3),<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><tr><td>Briancon (4), Torino (6) e Asiago (3).<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Nel girone di qualificazione gli allievi incontrano nella Bocconi un serio ostacolo da superare, al contrario nettamente inferiori i giovani del Milaninter. Il Torino, perso il sostegno Fiat, rinuncia ed \u00e8 un peccato perch\u00e9 lo scorso anno i giovani piemontesi si erano battuti molto bene.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"944\" height=\"711\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1.png\" alt=\"\" class=\"wp-image-14645\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1.png 944w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-300x226.png 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-768x578.png 768w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-100x75.png 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-50x38.png 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-25x19.png 25w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/09\/58-foto-Allievi-AmM-Bressan-1-740x557.png 740w\" sizes=\"(max-width: 944px) 100vw, 944px\" \/><figcaption><em>Da sinistra in piedi: Bressan, Sarfatti, Migliaresi, GF. Rigamonti, Montanari, Zappettini, Cauli. In prima fila: Arangia, Gino Rinaldi, Giovanni Pezzaglia.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Campionato allievi &#8211; Girone A<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Risultato<\/td><\/tr><tr><td>21 gennaio<\/td><td>Bocconi-Amatori Milano<\/td><td class=\"has-text-align-center\" data-align=\"center\">0-1<\/td><\/tr><tr><td>27 gennaio<\/td><td>Amatori Milano-Bocconi<\/td><td class=\"has-text-align-center\" data-align=\"center\">2-0<\/td><\/tr><tr><td>1 febbraio<\/td><td>Amatori Milano-Milaninter<\/td><td class=\"has-text-align-center\" data-align=\"center\">6-1<\/td><\/tr><tr><td>3 febbraio<\/td><td>Milaninter-Amatori Milano<\/td><td class=\"has-text-align-center\" data-align=\"center\">0-9<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Girone finale a Ortisei. In Val Gardena si disputano solo le prime due partite, il rialzo della temperatura rende impraticabile la pista e il match decisivo viene spostato a Bolzano.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite.jpg\" alt=\"\" class=\"wp-image-11522\" width=\"512\" height=\"575\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite.jpg 596w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite-267x300.jpg 267w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite-89x100.jpg 89w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite-45x50.jpg 45w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-GFA-Amatori-2-partite-22x25.jpg 22w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><figcaption><em>Articoli da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Campionato allievi &#8211; Girone finale<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>Bolzano, 10 febbraio<\/td><td>Ortisei-Alleghe<\/td><td>5-1 (1-0; 0-0; 4-1)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Ortisei campione nazionale allievi per il quarto anno consecutivo. Grazie a un buon numero di giovani impiegati e ben rodati dal Monte Civetta in Promozione (deroga FISG), si pensava che l&#8217;Alleghe potesse tentare il colpaccio, ma i gardenesi si sono ancora una volta dimostrati superiori agli avversari. Vinte tutte le partite, anche quelle del girone di qualificazione con Bolzano, Scoiattoli e SSV.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"896\" height=\"654\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei.jpg\" alt=\"\" class=\"wp-image-11523\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei.jpg 896w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-300x219.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-768x561.jpg 768w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-100x73.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-50x36.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-25x18.jpg 25w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.07-foto-AmMi-a-Ortisei-740x540.jpg 740w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><figcaption><em>Amatori a Ortisei, da sinistra in piedi: l&#8217;allenatore Pier Paolo Sommariva, GF. Rigamonti, Migliaresi, Zappettini, Cauli, Sarfatti, Bressan, Arangia. In basso: Montanari, G. Rinaldi, Signorini, G. Pezzaglia. Manca Frigerio.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">La stagione milanese si chiude al Palazzo con il torneo Targa dei Giovani.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Milano &#8211; Targa dei Giovani.<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>26 marzo<\/td><td>Bocconi-Milaninter<\/td><td>4-1<\/td><\/tr><tr><td>28 marzo<\/td><td>Milaninter-Amatori Milano<\/td><td>0-0<\/td><\/tr><tr><td>29 marzo<\/td><td>Amatori Milano-Bocconi<\/td><td>1-0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"346\" height=\"529\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov..jpg\" alt=\"\" class=\"wp-image-11754\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov..jpg 346w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov.-196x300.jpg 196w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov.-65x100.jpg 65w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov.-33x50.jpg 33w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.28-All.-AmM-MIHC-0-0-targa-giov.-16x25.jpg 16w\" sizes=\"(max-width: 346px) 100vw, 346px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"669\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia.jpg\" alt=\"\" class=\"wp-image-11755\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia-135x300.jpg 135w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia-45x100.jpg 45w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia-22x50.jpg 22w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2022\/01\/58.03.29-All.-AmM-Bocc-1-0-targa-giov.-Copia-11x25.jpg 11w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1.jpg\" alt=\"\" class=\"wp-image-10981\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1-150x150.jpg 150w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1-100x100.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1-50x50.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1-25x25.jpg 25w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/10\/logo-bocconi2nd-300x300-1-90x90.jpg 90w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td>Presidente<\/td><td>Guido Coppini<\/td><\/tr><tr><td>Allenatore<\/td><td>Alfio Tuzzi<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Ruolo<\/td><td><strong>Giocatori con almeno una presenza in prima squadra.<\/strong><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">P<\/td><td>Tonino Ingegnoli, Masotti, Visigalli.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">D<\/td><td>Arcangeli, Maurelio Bianchi, Ezio Castiglioni, Antonio Pizzi, Alfio Tuzzi, Giovanni Volpe.<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">A<\/td><td>Leonardo Carmignani, Federico Cerutti, Cristofoli, Otello Gangini, Garofalo, Marchetto, Mario Paracchini, Bruno Pizzi, Mario Vaccani.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Biancazzurri in costante miglioramento, il gap della prima squadra con l&#8217;Amatori si riduce e gli allievi non sono da meno. Brutta avventura nella trasferta di Asiago, ma poteva finire decisamente peggio.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1957<\/strong><\/td><td><strong>Camp. di Promozione &#8211; Girone A<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>Milano, 16 dicembre<\/td><td>Amatori Milano-Bocconi<\/td><td>4-2 (1-0; 0-1; 3-1)<\/td><\/tr><tr><td>Milano, 23 dicembre<\/td><td>Bocconi-Torino<\/td><td>4-7 (2-3; 2-1; 0-3)<\/td><\/tr><tr><td>Asiago, 29 dicembre<\/td><td>Asiago-Bocconi<\/td><td>13-3 (5-2; 3-1; 5-0)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"628\" height=\"350\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist..jpg\" alt=\"\" class=\"wp-image-11544\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist..jpg 628w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist.-300x167.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist.-100x56.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist.-50x28.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Boc-13-3-sist.-25x14.jpg 25w\" sizes=\"(max-width: 628px) 100vw, 628px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist.jpg\" alt=\"\" class=\"wp-image-11535\" width=\"567\" height=\"468\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist.jpg 727w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist-300x248.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist-100x83.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist-50x41.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.29-PA-Asi-Bocc-13-3-pullman-sist-25x21.jpg 25w\" sizes=\"(max-width: 567px) 100vw, 567px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Il torneo cadetto prosegue con la trasferta di Torino. Gli arbitri rilevano che la pista non \u00e8 tracciata secondo le misure prestabilite e da regolamento la partita non pu\u00f2 avere luogo: inevitabile la vittoria a tavolino della formazione milanese. Per non rendere inutile il viaggio effettuato da  milanesi e arbitri si decide di giocare un&#8217;amichevole.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav..jpg\" alt=\"\" class=\"wp-image-11566\" width=\"360\" height=\"446\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav..jpg 405w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav.-242x300.jpg 242w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav.-81x100.jpg 81w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav.-40x50.jpg 40w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.16-PA-To-Bocc-0-5-tav.-20x25.jpg 20w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"has-text-align-center\">Il derby di ritorno con l&#8217;Amatori e la partita al Palazzo con l&#8217;Asiago scrivono la parola fine alla stagione della prima squadra.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist.jpg\" alt=\"\" class=\"wp-image-11483\" width=\"362\" height=\"353\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist.jpg 593w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist-300x293.jpg 300w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist-100x98.jpg 100w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist-50x50.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.30-PA-AmM-Boc-4-2-sist-25x25.jpg 25w\" sizes=\"(max-width: 362px) 100vw, 362px\" \/><figcaption>Da &#8220;La Gazzetta dello Sport&#8221;. <\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"360\" height=\"504\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12.jpg\" alt=\"\" class=\"wp-image-11567\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12.jpg 360w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12-214x300.jpg 214w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12-71x100.jpg 71w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12-36x50.jpg 36w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.02.09-PA-Bocc-Asia-1-12-18x25.jpg 18w\" sizes=\"(max-width: 360px) 100vw, 360px\" \/><figcaption><em>Da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>Camp. di Promozione &#8211; Classifica finale del girone A <\/strong><\/td><\/tr><tr><td>Amatori Milano punti 11, Asiago 9, Torino e Bocconi 2.<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>Classifica marcatori stagionali Bocconi<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Reti<\/td><\/tr><tr><td>Leonardo Carmignani<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>Ico Cerutti, Otello Gangini e Mario Vaccani<\/td><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><\/tr><tr><td>Bruno Pizzi<\/td><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><\/tr><tr><td>Reti a tavolino<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><\/tr><tr><td>Mancano i marcatori di 2 reti segnate al Torino.<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">Nel campionato allievi il Milaninter non \u00e8 un avversario irresistibile, ma per accedere al girone finale bisogna fare i conti con l&#8217;Amatori.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1.jpg\" alt=\"\" class=\"wp-image-11571\" width=\"388\" height=\"399\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1.jpg 473w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1-292x300.jpg 292w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1-97x100.jpg 97w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1-50x50.jpg 50w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/57.12.21-All-Bocc-MIHC-14-1-25x25.jpg 25w\" sizes=\"(max-width: 388px) 100vw, 388px\" \/><figcaption><em>Da &#8220;La Gazzetta dello Sport&#8221;.<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7.jpg\" alt=\"\" class=\"wp-image-11572\" width=\"383\" height=\"463\" srcset=\"https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7.jpg 460w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7-248x300.jpg 248w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7-83x100.jpg 83w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7-41x50.jpg 41w, https:\/\/www.milanosiamonoi.com\/wp-content\/uploads\/2021\/11\/58.01.14-All-MIHC-Boc-0-7-21x25.jpg 21w\" sizes=\"(max-width: 383px) 100vw, 383px\" \/><figcaption><em>Articolo da &#8220;La Gazzetta dello Sport&#8221;<\/em><\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Campionato allievi &#8211; Girone A<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>21 gennaio<\/td><td>Bocconi-Amatori Milano<\/td><td>0-1<\/td><\/tr><tr><td>27 gennaio<\/td><td>Amatori Milano-Bocconi<\/td><td>2-0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">I bocconiani danno il massimo in entrambi i derby, ma a spuntarla \u00e8 sempre l&#8217;Amatori. I biancazzurri cercheranno la rivincita nel torneo di fine stagione con in palio la Targa dei Giovani.<\/p>\n\n\n\n<figure class=\"wp-block-table aligncenter\"><table><tbody><tr><td><strong>1958<\/strong><\/td><td><strong>Milano &#8211; Targa dei Giovani.<\/strong><\/td><td>Risultato<\/td><\/tr><tr><td>26 marzo<\/td><td>Bocconi-Milaninter<\/td><td>4-1<\/td><\/tr><tr><td>28 marzo<\/td><td>Milaninter-Amatori Milano<\/td><td>0-0<\/td><\/tr><tr><td>29 marzo<\/td><td>Amatori Milano-Bocconi<\/td><td>1-0<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p class=\"has-text-align-center\">La Targa finisce nella bacheca degli amatorini, giovani biancazzurri pari ai rivali, ma anche questa volta il risultato non li premia. Rispetto alle partite di campionato \u00e8 notevole il miglioramento della squadra rossonerazzurra, il lavoro di Aldo Federici d\u00e0 i suoi frutti. <\/p>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td><strong><a href=\"https:\/\/www.milanosiamonoi.com\/index.php\/campionati\/dal-1950-al-1959-anni-doro\/1956-1957-amatori-mi-e-bocconi\/\">stagione precedente<\/a><\/strong><\/td><td class=\"has-text-align-right\" data-align=\"right\"><strong><a href=\"https:\/\/www.milanosiamonoi.com\/index.php\/campionati\/dal-1950-al-1959-anni-doro\/1958-1959-amatori-mi-bocconi-e-allievi\/\">stagione successiva<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<figure class=\"wp-block-table\"><table><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><a href=\"https:\/\/www.milanosiamonoi.com\/index.php\/campionati\/dal-1950-al-1959-anni-doro\/1957-1958-milaninter-hc\/\">MilanInter Hockey Club<\/a><\/strong><\/td><\/tr><\/tbody><\/table><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Presidente Floriano Mainoldi Allenatore Carlo Signorini Ruolo Giocatori con almeno una presenza in prima squadra. P Andrea Balzani, Piero Misul, Gino Rinaldi. D Franco Canepa,&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":1469,"menu_order":24,"comment_status":"closed","ping_status":"closed","template":"","meta":{"spay_email":"","footnotes":""},"_links":{"self":[{"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/pages\/11454"}],"collection":[{"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/comments?post=11454"}],"version-history":[{"count":107,"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/pages\/11454\/revisions"}],"predecessor-version":[{"id":16328,"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/pages\/11454\/revisions\/16328"}],"up":[{"embeddable":true,"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/pages\/1469"}],"wp:attachment":[{"href":"https:\/\/www.milanosiamonoi.com\/index.php\/wp-json\/wp\/v2\/media?parent=11454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}